{"id":9486,"count":3,"description":"","link":"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/","name":"Arnold Schwarzenegger","slug":"arnold-schwarzenegger","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arnold Schwarzenegger | Arcader News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arnold Schwarzenegger | Arcader News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcade News\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arcader.org\/wp-content\/uploads\/2020\/11\/cropped-arcader-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/tag\\\/arnold-schwarzenegger\\\/\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/tag\\\/arnold-schwarzenegger\\\/\",\"name\":\"Arnold Schwarzenegger | Arcader News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/tag\\\/arnold-schwarzenegger\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/tag\\\/arnold-schwarzenegger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arcader.org\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arnold Schwarzenegger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/\",\"name\":\"Arcade News\",\"description\":\"Free Arcade News from the Best Online Sources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arcader.org\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arnold Schwarzenegger | Arcader News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/","og_locale":"en_US","og_type":"article","og_title":"Arnold Schwarzenegger | Arcader News","og_url":"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/","og_site_name":"Arcade News","og_image":[{"width":480,"height":320,"url":"https:\/\/arcader.org\/wp-content\/uploads\/2020\/11\/cropped-arcader-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/","url":"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/","name":"Arnold Schwarzenegger | Arcader News","isPartOf":{"@id":"https:\/\/arcader.org\/news\/#website"},"breadcrumb":{"@id":"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/arcader.org\/news\/tag\/arnold-schwarzenegger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arcader.org\/news\/"},{"@type":"ListItem","position":2,"name":"Arnold Schwarzenegger"}]},{"@type":"WebSite","@id":"https:\/\/arcader.org\/news\/#website","url":"https:\/\/arcader.org\/news\/","name":"Arcade News","description":"Free Arcade News from the Best Online Sources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arcader.org\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/tags\/9486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts?tags=9486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}