{"id":982258,"date":"2026-01-06T15:47:19","date_gmt":"2026-01-06T15:47:19","guid":{"rendered":"https:\/\/www.eurogamer.net\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster"},"modified":"2026-01-06T15:47:19","modified_gmt":"2026-01-06T15:47:19","slug":"capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster","status":"publish","type":"post","link":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/","title":{"rendered":"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/arcader.org\/wp-content\/uploads\/2024\/09\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg\" \/> <\/p>\n<p>Fender has teamed up with Capcom to create a Telecaster inspired by <a data-keyword=\"true\" href=\"https:\/\/www.eurogamer.net\/games\/monster-hunter\">Monster Hunter<\/a>: the Monster Hunter Rathalos Telecaster.<\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\">Read more<\/a><\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\">Source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fender has teamed up with Capcom to create a Telecaster inspired by Monster Hunter: the Monster Hunter Rathalos Telecaster. Read more Source<\/p>\n","protected":false},"author":1,"featured_media":982259,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230],"tags":[209,1694,6299,6881,11122,59,45,34,8822,54,3987,4616],"class_list":["post-982258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eurogamer","tag-capcom","tag-collaboration","tag-guitar","tag-hackslash","tag-monster-hunter-wilds","tag-pc","tag-ps5","tag-rpg","tag-rpg-action","tag-single-player","tag-third-person","tag-xbox-series-x-s"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capcom teams up with Fender for this Monster Hunter-inspired Telecaster | Arcader News<\/title>\n<meta name=\"description\" content=\"Fender has teamed up with Capcom to create a Telecaster inspired by Monster Hunter: the Monster Hunter Rathalos Telecaster. Read moreSource\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster | Arcader News\" \/>\n<meta property=\"og:description\" content=\"Fender has teamed up with Capcom to create a Telecaster inspired by Monster Hunter: the Monster Hunter Rathalos Telecaster. Read moreSource\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcade News\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T15:47:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arcader.org\/wp-content\/uploads\/2024\/09\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arcade News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcade News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/\"},\"author\":{\"name\":\"Arcade News\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"headline\":\"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster\",\"datePublished\":\"2026-01-06T15:47:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/\"},\"wordCount\":32,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg\",\"keywords\":[\"Capcom\",\"collaboration\",\"guitar\",\"Hack&amp;Slash\",\"Monster Hunter Wilds\",\"PC\",\"PS5\",\"RPG\",\"RPG: Action\",\"single-player\",\"Third Person\",\"Xbox Series X\\\/S\"],\"articleSection\":[\"Eurogamer\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/\",\"name\":\"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster | Arcader News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg\",\"datePublished\":\"2026-01-06T15:47:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"description\":\"Fender has teamed up with Capcom to create a Telecaster inspired by Monster Hunter: the Monster Hunter Rathalos Telecaster. Read moreSource\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg\",\"contentUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg\",\"width\":480,\"height\":325,\"caption\":\"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arcader.org\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/\",\"name\":\"Arcade News\",\"description\":\"Free Arcade News from the Best Online Sources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arcader.org\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\",\"name\":\"Arcade News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"caption\":\"Arcade News\"},\"sameAs\":[\"https:\\\/\\\/cricketgames.tv\"],\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/author\\\/arcade-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster | Arcader News","description":"Fender has teamed up with Capcom to create a Telecaster inspired by Monster Hunter: the Monster Hunter Rathalos Telecaster. Read moreSource","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/","og_locale":"en_US","og_type":"article","og_title":"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster | Arcader News","og_description":"Fender has teamed up with Capcom to create a Telecaster inspired by Monster Hunter: the Monster Hunter Rathalos Telecaster. Read moreSource","og_url":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/","og_site_name":"Arcade News","article_published_time":"2026-01-06T15:47:19+00:00","og_image":[{"width":480,"height":325,"url":"https:\/\/arcader.org\/wp-content\/uploads\/2024\/09\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg","type":"image\/jpeg"}],"author":"Arcade News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arcade News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#article","isPartOf":{"@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/"},"author":{"name":"Arcade News","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"headline":"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster","datePublished":"2026-01-06T15:47:19+00:00","mainEntityOfPage":{"@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/"},"wordCount":32,"commentCount":0,"image":{"@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2024\/09\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg","keywords":["Capcom","collaboration","guitar","Hack&amp;Slash","Monster Hunter Wilds","PC","PS5","RPG","RPG: Action","single-player","Third Person","Xbox Series X\/S"],"articleSection":["Eurogamer"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/","url":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/","name":"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster | Arcader News","isPartOf":{"@id":"https:\/\/arcader.org\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#primaryimage"},"image":{"@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2024\/09\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg","datePublished":"2026-01-06T15:47:19+00:00","author":{"@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"description":"Fender has teamed up with Capcom to create a Telecaster inspired by Monster Hunter: the Monster Hunter Rathalos Telecaster. Read moreSource","breadcrumb":{"@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#primaryimage","url":"https:\/\/arcader.org\/wp-content\/uploads\/2024\/09\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg","contentUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2024\/09\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster.jpg","width":480,"height":325,"caption":"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster"},{"@type":"BreadcrumbList","@id":"https:\/\/arcader.org\/news\/capcom-teams-up-with-fender-for-this-monster-hunter-inspired-telecaster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arcader.org\/news\/"},{"@type":"ListItem","position":2,"name":"Capcom teams up with Fender for this Monster Hunter-inspired Telecaster"}]},{"@type":"WebSite","@id":"https:\/\/arcader.org\/news\/#website","url":"https:\/\/arcader.org\/news\/","name":"Arcade News","description":"Free Arcade News from the Best Online Sources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arcader.org\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839","name":"Arcade News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","caption":"Arcade News"},"sameAs":["https:\/\/cricketgames.tv"],"url":"https:\/\/arcader.org\/news\/author\/arcade-news\/"}]}},"_links":{"self":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/982258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/comments?post=982258"}],"version-history":[{"count":1,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/982258\/revisions"}],"predecessor-version":[{"id":1452425,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/982258\/revisions\/1452425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media\/982259"}],"wp:attachment":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media?parent=982258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/categories?post=982258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/tags?post=982258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}