{"id":662424,"date":"2026-04-02T10:15:13","date_gmt":"2026-04-02T10:15:13","guid":{"rendered":"https:\/\/www.eurogamer.net\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks"},"modified":"2026-04-02T10:15:13","modified_gmt":"2026-04-02T10:15:13","slug":"diablo-immortal-passes-100m-revenue-after-just-eight-weeks","status":"publish","type":"post","link":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/","title":{"rendered":"Diablo Immortal passes $100m revenue after just eight weeks"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/arcader.org\/wp-content\/uploads\/2022\/07\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg\" \/> <\/p>\n<p>\nBlizzard and NetEase&#8217;s Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game&#8217;s Chinese market. <\/p>\n<p>\nThat&#8217;s according to reliable app store analytics firm <a href=\"https:\/\/sensortower.com\/blog\/diablo-immortal-mobile-100-million-revenue\">Sensor Tower<\/a>, which compared Diablo Immortal&#8217;s start to that of Pok&eacute;mon Go (which took just two weeks to rake in $100m) and Fire Emblem Heroes (10 weeks). <\/p>\n<p>\nDiablo Immortal revenues now seem set to accelerate, since the app arrived belatedly in China this week.\n<\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\">Read more<\/a><\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\">Source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blizzard and NetEase&#8217;s Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game&#8217;s Chinese market. That&#8217;s according to reliable app store analytics firm Sensor Tower, which compared Diablo Immortal&#8217;s start to that of Pok&eacute;mon Go (which took just two weeks to rake in $100m) and Fire Emblem Heroes (10 weeks). Diablo Immortal revenues now seem set to accelerate, since the app arrived belatedly in China this week. Read more Source<\/p>\n","protected":false},"author":1,"featured_media":662425,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230],"tags":[1433],"class_list":["post-662424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eurogamer","tag-diablo-immortal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diablo Immortal passes $100m revenue after just eight weeks | Arcader News<\/title>\n<meta name=\"description\" content=\"Blizzard and NetEase&#039;s Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game&#039;s Chinese market. That&#039;s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diablo Immortal passes $100m revenue after just eight weeks | Arcader News\" \/>\n<meta property=\"og:description\" content=\"Blizzard and NetEase&#039;s Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game&#039;s Chinese market. That&#039;s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcade News\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T10:15:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arcader.org\/wp-content\/uploads\/2022\/07\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arcade News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcade News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/\"},\"author\":{\"name\":\"Arcade News\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"headline\":\"Diablo Immortal passes $100m revenue after just eight weeks\",\"datePublished\":\"2026-04-02T10:15:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/\"},\"wordCount\":91,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg\",\"keywords\":[\"diablo-immortal\"],\"articleSection\":[\"Eurogamer\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/\",\"name\":\"Diablo Immortal passes $100m revenue after just eight weeks | Arcader News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg\",\"datePublished\":\"2026-04-02T10:15:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"description\":\"Blizzard and NetEase's Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game's Chinese market. That's\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg\",\"contentUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg\",\"width\":480,\"height\":270,\"caption\":\"Diablo Immortal passes $100m revenue after just eight weeks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arcader.org\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diablo Immortal passes $100m revenue after just eight weeks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/\",\"name\":\"Arcade News\",\"description\":\"Free Arcade News from the Best Online Sources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arcader.org\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\",\"name\":\"Arcade News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"caption\":\"Arcade News\"},\"sameAs\":[\"https:\\\/\\\/cricketgames.tv\"],\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/author\\\/arcade-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diablo Immortal passes $100m revenue after just eight weeks | Arcader News","description":"Blizzard and NetEase's Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game's Chinese market. That's","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/","og_locale":"en_US","og_type":"article","og_title":"Diablo Immortal passes $100m revenue after just eight weeks | Arcader News","og_description":"Blizzard and NetEase's Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game's Chinese market. That's","og_url":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/","og_site_name":"Arcade News","article_published_time":"2026-04-02T10:15:13+00:00","og_image":[{"width":480,"height":270,"url":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/07\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg","type":"image\/jpeg"}],"author":"Arcade News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arcade News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#article","isPartOf":{"@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/"},"author":{"name":"Arcade News","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"headline":"Diablo Immortal passes $100m revenue after just eight weeks","datePublished":"2026-04-02T10:15:13+00:00","mainEntityOfPage":{"@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/"},"wordCount":91,"commentCount":0,"image":{"@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/07\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg","keywords":["diablo-immortal"],"articleSection":["Eurogamer"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/","url":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/","name":"Diablo Immortal passes $100m revenue after just eight weeks | Arcader News","isPartOf":{"@id":"https:\/\/arcader.org\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#primaryimage"},"image":{"@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/07\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg","datePublished":"2026-04-02T10:15:13+00:00","author":{"@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"description":"Blizzard and NetEase's Diablo Immortal has notched up $100m in player spending after two months, almost entirely without the game's Chinese market. That's","breadcrumb":{"@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#primaryimage","url":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/07\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg","contentUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/07\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks.jpg","width":480,"height":270,"caption":"Diablo Immortal passes $100m revenue after just eight weeks"},{"@type":"BreadcrumbList","@id":"https:\/\/arcader.org\/news\/diablo-immortal-passes-100m-revenue-after-just-eight-weeks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arcader.org\/news\/"},{"@type":"ListItem","position":2,"name":"Diablo Immortal passes $100m revenue after just eight weeks"}]},{"@type":"WebSite","@id":"https:\/\/arcader.org\/news\/#website","url":"https:\/\/arcader.org\/news\/","name":"Arcade News","description":"Free Arcade News from the Best Online Sources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arcader.org\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839","name":"Arcade News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","caption":"Arcade News"},"sameAs":["https:\/\/cricketgames.tv"],"url":"https:\/\/arcader.org\/news\/author\/arcade-news\/"}]}},"_links":{"self":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/662424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/comments?post=662424"}],"version-history":[{"count":1,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/662424\/revisions"}],"predecessor-version":[{"id":1294557,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/662424\/revisions\/1294557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media\/662425"}],"wp:attachment":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media?parent=662424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/categories?post=662424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/tags?post=662424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}