{"id":592269,"date":"2026-03-19T06:55:41","date_gmt":"2026-03-19T06:55:41","guid":{"rendered":"https:\/\/www.eurogamer.net\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities"},"modified":"2026-03-19T06:55:41","modified_gmt":"2026-03-19T06:55:41","slug":"eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities","status":"publish","type":"post","link":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/","title":{"rendered":"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/arcader.org\/wp-content\/uploads\/2022\/05\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg\" \/> <\/p>\n<p>\nEurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. <\/p>\n<p>\nThe programme will once again run for two months this summer, with applications now open, exclusively to those from ethnic minorities who live in the UK. <\/p>\n<p>\nAs we wrote last year when launching the scheme initially, the games media has a diversity problem and Eurogamer is no exception. It is on us to help affect change and continue improving representation, so that the games media better reflects the gaming community as a whole.\n<\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\">Read more<\/a><\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\">Source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. The programme will once again run for two months this summer, with applications now open, exclusively to those from ethnic minorities who live in the UK. As we wrote last year when launching the scheme initially, the games media has a diversity problem and Eurogamer is no exception. It is on us to help affect change and continue improving representation, so that the games media better reflects the gaming community as a whole. Read more Source<\/p>\n","protected":false},"author":1,"featured_media":592270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230],"tags":[4316],"class_list":["post-592269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eurogamer","tag-eurogamer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eurogamer launches summer 2022 paid work experience programme for ethnic minorities | Arcader News<\/title>\n<meta name=\"description\" content=\"Eurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. The\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities | Arcader News\" \/>\n<meta property=\"og:description\" content=\"Eurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. The\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcade News\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T06:55:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arcader.org\/wp-content\/uploads\/2022\/05\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arcade News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcade News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/\"},\"author\":{\"name\":\"Arcade News\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"headline\":\"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities\",\"datePublished\":\"2026-03-19T06:55:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/\"},\"wordCount\":108,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg\",\"keywords\":[\"eurogamer\"],\"articleSection\":[\"Eurogamer\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/\",\"name\":\"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities | Arcader News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg\",\"datePublished\":\"2026-03-19T06:55:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"description\":\"Eurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. The\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg\",\"contentUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg\",\"width\":480,\"height\":269,\"caption\":\"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arcader.org\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/\",\"name\":\"Arcade News\",\"description\":\"Free Arcade News from the Best Online Sources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arcader.org\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\",\"name\":\"Arcade News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"caption\":\"Arcade News\"},\"sameAs\":[\"https:\\\/\\\/cricketgames.tv\"],\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/author\\\/arcade-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities | Arcader News","description":"Eurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. The","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/","og_locale":"en_US","og_type":"article","og_title":"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities | Arcader News","og_description":"Eurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. The","og_url":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/","og_site_name":"Arcade News","article_published_time":"2026-03-19T06:55:41+00:00","og_image":[{"width":480,"height":269,"url":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/05\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg","type":"image\/jpeg"}],"author":"Arcade News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arcade News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#article","isPartOf":{"@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/"},"author":{"name":"Arcade News","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"headline":"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities","datePublished":"2026-03-19T06:55:41+00:00","mainEntityOfPage":{"@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/"},"wordCount":108,"commentCount":0,"image":{"@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/05\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg","keywords":["eurogamer"],"articleSection":["Eurogamer"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/","url":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/","name":"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities | Arcader News","isPartOf":{"@id":"https:\/\/arcader.org\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#primaryimage"},"image":{"@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/05\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg","datePublished":"2026-03-19T06:55:41+00:00","author":{"@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"description":"Eurogamer is delighted to announce the return of its paid work experience programme for ethnic minorities, following its successful debut last year. The","breadcrumb":{"@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#primaryimage","url":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/05\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg","contentUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2022\/05\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities.jpg","width":480,"height":269,"caption":"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities"},{"@type":"BreadcrumbList","@id":"https:\/\/arcader.org\/news\/eurogamer-launches-summer-2022-paid-work-experience-programme-for-ethnic-minorities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arcader.org\/news\/"},{"@type":"ListItem","position":2,"name":"Eurogamer launches summer 2022 paid work experience programme for ethnic minorities"}]},{"@type":"WebSite","@id":"https:\/\/arcader.org\/news\/#website","url":"https:\/\/arcader.org\/news\/","name":"Arcade News","description":"Free Arcade News from the Best Online Sources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arcader.org\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839","name":"Arcade News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","caption":"Arcade News"},"sameAs":["https:\/\/cricketgames.tv"],"url":"https:\/\/arcader.org\/news\/author\/arcade-news\/"}]}},"_links":{"self":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/592269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/comments?post=592269"}],"version-history":[{"count":1,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/592269\/revisions"}],"predecessor-version":[{"id":1278743,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/592269\/revisions\/1278743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media\/592270"}],"wp:attachment":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media?parent=592269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/categories?post=592269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/tags?post=592269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}