{"id":1577745,"date":"2026-05-13T13:21:30","date_gmt":"2026-05-13T13:21:30","guid":{"rendered":"https:\/\/www.eurogamer.net\/uncharted-4-amy-hennig-original-version-elena-fisher-cut-content"},"modified":"2026-05-13T13:21:30","modified_gmt":"2026-05-13T13:21:30","slug":"uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher","status":"publish","type":"post","link":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/","title":{"rendered":"Uncharted 4&#8217;s binned original version would have had a much bigger role for Nathan Drake&#8217;s love interest, Elena Fisher"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/arcader.org\/wp-content\/uploads\/2026\/05\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg\" \/> <\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/games\/uncharted-4-thiefs-end\">Uncharted 4: A Thief&#8217;s End<\/a> recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what Amy Hennig&#8217;s original version of the game could have looked like.<\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/uncharted-4-amy-hennig-original-version-elena-fisher-cut-content\">Read more<\/a><\/p>\n<p><a href=\"https:\/\/www.eurogamer.net\/uncharted-4-amy-hennig-original-version-elena-fisher-cut-content\">Source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uncharted 4: A Thief&#8217;s End recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what Amy Hennig&#8217;s original version of the game could have looked like. Read more Source<\/p>\n","protected":false},"author":1,"featured_media":1577746,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230],"tags":[259,8711,778,44,86,54,4770,3987,6346],"class_list":["post-1577745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eurogamer","tag-action-adventure","tag-multiplayer-competitive","tag-naughty-dog","tag-ps4","tag-shooter","tag-single-player","tag-sony-computer-entertainment","tag-third-person","tag-uncharted-4-a-thiefs-end"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncharted 4&#039;s binned original version would have had a much bigger role for Nathan Drake&#039;s love interest, Elena Fisher | Arcader News<\/title>\n<meta name=\"description\" content=\"Uncharted 4: A Thief&#039;s End recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncharted 4&#039;s binned original version would have had a much bigger role for Nathan Drake&#039;s love interest, Elena Fisher | Arcader News\" \/>\n<meta property=\"og:description\" content=\"Uncharted 4: A Thief&#039;s End recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcade News\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T13:21:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arcader.org\/wp-content\/uploads\/2026\/05\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg\" \/>\n<meta name=\"author\" content=\"Arcade News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcade News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/\"},\"author\":{\"name\":\"Arcade News\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"headline\":\"Uncharted 4&#8217;s binned original version would have had a much bigger role for Nathan Drake&#8217;s love interest, Elena Fisher\",\"datePublished\":\"2026-05-13T13:21:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/\"},\"wordCount\":59,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg\",\"keywords\":[\"Action-Adventure\",\"Multiplayer Competitive\",\"naughty dog\",\"PS4\",\"Shooter\",\"single-player\",\"sony computer entertainment\",\"Third Person\",\"uncharted 4: a thief's end\"],\"articleSection\":[\"Eurogamer\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/\",\"name\":\"Uncharted 4's binned original version would have had a much bigger role for Nathan Drake's love interest, Elena Fisher | Arcader News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg\",\"datePublished\":\"2026-05-13T13:21:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"description\":\"Uncharted 4: A Thief's End recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg\",\"contentUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg\",\"width\":480,\"height\":270,\"caption\":\"Uncharted 4\u2019s binned original version would have had a much bigger role for Nathan Drake\u2019s love interest, Elena Fisher\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arcader.org\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncharted 4&#8217;s binned original version would have had a much bigger role for Nathan Drake&#8217;s love interest, Elena Fisher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/\",\"name\":\"Arcade News\",\"description\":\"Free Arcade News from the Best Online Sources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arcader.org\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\",\"name\":\"Arcade News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"caption\":\"Arcade News\"},\"sameAs\":[\"https:\\\/\\\/cricketgames.tv\"],\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/author\\\/arcade-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncharted 4's binned original version would have had a much bigger role for Nathan Drake's love interest, Elena Fisher | Arcader News","description":"Uncharted 4: A Thief's End recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/","og_locale":"en_US","og_type":"article","og_title":"Uncharted 4's binned original version would have had a much bigger role for Nathan Drake's love interest, Elena Fisher | Arcader News","og_description":"Uncharted 4: A Thief's End recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what","og_url":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/","og_site_name":"Arcade News","article_published_time":"2026-05-13T13:21:30+00:00","og_image":[{"url":"https:\/\/arcader.org\/wp-content\/uploads\/2026\/05\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg","type":"","width":"","height":""}],"author":"Arcade News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arcade News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#article","isPartOf":{"@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/"},"author":{"name":"Arcade News","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"headline":"Uncharted 4&#8217;s binned original version would have had a much bigger role for Nathan Drake&#8217;s love interest, Elena Fisher","datePublished":"2026-05-13T13:21:30+00:00","mainEntityOfPage":{"@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/"},"wordCount":59,"commentCount":0,"image":{"@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2026\/05\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg","keywords":["Action-Adventure","Multiplayer Competitive","naughty dog","PS4","Shooter","single-player","sony computer entertainment","Third Person","uncharted 4: a thief's end"],"articleSection":["Eurogamer"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/","url":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/","name":"Uncharted 4's binned original version would have had a much bigger role for Nathan Drake's love interest, Elena Fisher | Arcader News","isPartOf":{"@id":"https:\/\/arcader.org\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#primaryimage"},"image":{"@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2026\/05\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg","datePublished":"2026-05-13T13:21:30+00:00","author":{"@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"description":"Uncharted 4: A Thief's End recently celebrated its 10th anniversary, and to mark the occasion YouTuber Thekempy has released a deep dive exploring what","breadcrumb":{"@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#primaryimage","url":"https:\/\/arcader.org\/wp-content\/uploads\/2026\/05\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg","contentUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2026\/05\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher.jpg","width":480,"height":270,"caption":"Uncharted 4\u2019s binned original version would have had a much bigger role for Nathan Drake\u2019s love interest, Elena Fisher"},{"@type":"BreadcrumbList","@id":"https:\/\/arcader.org\/news\/uncharted-4s-binned-original-version-would-have-had-a-much-bigger-role-for-nathan-drakes-love-interest-elena-fisher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arcader.org\/news\/"},{"@type":"ListItem","position":2,"name":"Uncharted 4&#8217;s binned original version would have had a much bigger role for Nathan Drake&#8217;s love interest, Elena Fisher"}]},{"@type":"WebSite","@id":"https:\/\/arcader.org\/news\/#website","url":"https:\/\/arcader.org\/news\/","name":"Arcade News","description":"Free Arcade News from the Best Online Sources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arcader.org\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839","name":"Arcade News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","caption":"Arcade News"},"sameAs":["https:\/\/cricketgames.tv"],"url":"https:\/\/arcader.org\/news\/author\/arcade-news\/"}]}},"_links":{"self":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/1577745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/comments?post=1577745"}],"version-history":[{"count":0,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/1577745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media\/1577746"}],"wp:attachment":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media?parent=1577745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/categories?post=1577745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/tags?post=1577745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}