{"id":1193504,"date":"2026-02-17T15:16:45","date_gmt":"2026-02-17T15:16:45","guid":{"rendered":"https:\/\/www.vg247.com\/oblivion-remastered-blind-lockpicking-mod"},"modified":"2026-02-17T15:16:45","modified_gmt":"2026-02-17T15:16:45","slug":"this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain","status":"publish","type":"post","link":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/","title":{"rendered":"&#8220;This mod feels like a threat&#8221; Oblivion Remastered&#8217;s lockpicking is already perfect for masochists, but here&#8217;s your chance to experience a new world of pain"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/arcader.org\/wp-content\/uploads\/2025\/05\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg\" \/> <\/p>\n<p>Uh oh. <a href=\"https:\/\/www.vg247.com\/games\/the-elder-scrolls-4-oblivion-remake\">Oblivion Remastered<\/a>&#8216;s lockpicking minigame can be just as brutal as the one you remember from the original, but if you&#8217;ve managed to master it, there&#8217;s a new mod that&#8217;ll add an extra layer of challenge. Fancy not even being able to see the pins you&#8217;re trying to flick up?<\/p>\n<p><a href=\"https:\/\/www.vg247.com\/oblivion-remastered-blind-lockpicking-mod\">Read more<\/a><\/p>\n<p><a href=\"https:\/\/www.vg247.com\/oblivion-remastered-blind-lockpicking-mod\">Source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uh oh. Oblivion Remastered&#8216;s lockpicking minigame can be just as brutal as the one you remember from the original, but if you&#8217;ve managed to master it, there&#8217;s a new mod that&#8217;ll add an extra layer of challenge. Fancy not even being able to see the pins you&#8217;re trying to flick up? Read more Source<\/p>\n","protected":false},"author":1,"featured_media":1193505,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[259,2879,773,505,59,45,34,54,17351,3987,8067,4616],"class_list":["post-1193504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vg24-7","tag-action-adventure","tag-bethesda-game-studios","tag-first-person","tag-mods","tag-pc","tag-ps5","tag-rpg","tag-single-player","tag-the-elder-scrolls-iv-oblivion-remastered","tag-third-person","tag-virtuos","tag-xbox-series-x-s"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;This mod feels like a threat&quot; Oblivion Remastered&#039;s lockpicking is already perfect for masochists, but here&#039;s your chance to experience a new world of pain | Arcader News<\/title>\n<meta name=\"description\" content=\"Uh oh. Oblivion Remastered&#039;s lockpicking minigame can be just as brutal as the one you remember from the original, but if you&#039;ve managed to master it,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;This mod feels like a threat&quot; Oblivion Remastered&#039;s lockpicking is already perfect for masochists, but here&#039;s your chance to experience a new world of pain | Arcader News\" \/>\n<meta property=\"og:description\" content=\"Uh oh. Oblivion Remastered&#039;s lockpicking minigame can be just as brutal as the one you remember from the original, but if you&#039;ve managed to master it,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcade News\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T15:16:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arcader.org\/wp-content\/uploads\/2025\/05\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arcade News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcade News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/\"},\"author\":{\"name\":\"Arcade News\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"headline\":\"&#8220;This mod feels like a threat&#8221; Oblivion Remastered&#8217;s lockpicking is already perfect for masochists, but here&#8217;s your chance to experience a new world of pain\",\"datePublished\":\"2026-02-17T15:16:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/\"},\"wordCount\":86,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg\",\"keywords\":[\"Action-Adventure\",\"bethesda game studios\",\"first-person\",\"mods\",\"PC\",\"PS5\",\"RPG\",\"single-player\",\"The Elder Scrolls IV: Oblivion Remastered\",\"Third Person\",\"Virtuos\",\"Xbox Series X\\\/S\"],\"articleSection\":[\"VG24\\\/7\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/\",\"name\":\"\\\"This mod feels like a threat\\\" Oblivion Remastered's lockpicking is already perfect for masochists, but here's your chance to experience a new world of pain | Arcader News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg\",\"datePublished\":\"2026-02-17T15:16:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\"},\"description\":\"Uh oh. Oblivion Remastered's lockpicking minigame can be just as brutal as the one you remember from the original, but if you've managed to master it,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg\",\"contentUrl\":\"https:\\\/\\\/arcader.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg\",\"width\":480,\"height\":270,\"caption\":\"\u201cThis mod feels like a threat\u201d Oblivion Remastered\u2019s lockpicking is already perfect for masochists, but here\u2019s your chance to experience a new world of pain\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arcader.org\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;This mod feels like a threat&#8221; Oblivion Remastered&#8217;s lockpicking is already perfect for masochists, but here&#8217;s your chance to experience a new world of pain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/\",\"name\":\"Arcade News\",\"description\":\"Free Arcade News from the Best Online Sources\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arcader.org\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arcader.org\\\/news\\\/#\\\/schema\\\/person\\\/8460f5e5076b52fb2369f2f7ce6f2839\",\"name\":\"Arcade News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g\",\"caption\":\"Arcade News\"},\"sameAs\":[\"https:\\\/\\\/cricketgames.tv\"],\"url\":\"https:\\\/\\\/arcader.org\\\/news\\\/author\\\/arcade-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"This mod feels like a threat\" Oblivion Remastered's lockpicking is already perfect for masochists, but here's your chance to experience a new world of pain | Arcader News","description":"Uh oh. Oblivion Remastered's lockpicking minigame can be just as brutal as the one you remember from the original, but if you've managed to master it,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/","og_locale":"en_US","og_type":"article","og_title":"\"This mod feels like a threat\" Oblivion Remastered's lockpicking is already perfect for masochists, but here's your chance to experience a new world of pain | Arcader News","og_description":"Uh oh. Oblivion Remastered's lockpicking minigame can be just as brutal as the one you remember from the original, but if you've managed to master it,","og_url":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/","og_site_name":"Arcade News","article_published_time":"2026-02-17T15:16:45+00:00","og_image":[{"width":480,"height":270,"url":"https:\/\/arcader.org\/wp-content\/uploads\/2025\/05\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg","type":"image\/jpeg"}],"author":"Arcade News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arcade News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#article","isPartOf":{"@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/"},"author":{"name":"Arcade News","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"headline":"&#8220;This mod feels like a threat&#8221; Oblivion Remastered&#8217;s lockpicking is already perfect for masochists, but here&#8217;s your chance to experience a new world of pain","datePublished":"2026-02-17T15:16:45+00:00","mainEntityOfPage":{"@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/"},"wordCount":86,"commentCount":0,"image":{"@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2025\/05\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg","keywords":["Action-Adventure","bethesda game studios","first-person","mods","PC","PS5","RPG","single-player","The Elder Scrolls IV: Oblivion Remastered","Third Person","Virtuos","Xbox Series X\/S"],"articleSection":["VG24\/7"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/","url":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/","name":"\"This mod feels like a threat\" Oblivion Remastered's lockpicking is already perfect for masochists, but here's your chance to experience a new world of pain | Arcader News","isPartOf":{"@id":"https:\/\/arcader.org\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#primaryimage"},"image":{"@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#primaryimage"},"thumbnailUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2025\/05\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg","datePublished":"2026-02-17T15:16:45+00:00","author":{"@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839"},"description":"Uh oh. Oblivion Remastered's lockpicking minigame can be just as brutal as the one you remember from the original, but if you've managed to master it,","breadcrumb":{"@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#primaryimage","url":"https:\/\/arcader.org\/wp-content\/uploads\/2025\/05\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg","contentUrl":"https:\/\/arcader.org\/wp-content\/uploads\/2025\/05\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain.jpg","width":480,"height":270,"caption":"\u201cThis mod feels like a threat\u201d Oblivion Remastered\u2019s lockpicking is already perfect for masochists, but here\u2019s your chance to experience a new world of pain"},{"@type":"BreadcrumbList","@id":"https:\/\/arcader.org\/news\/this-mod-feels-like-a-threat-oblivion-remastereds-lockpicking-is-already-perfect-for-masochists-but-heres-your-chance-to-experience-a-new-world-of-pain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arcader.org\/news\/"},{"@type":"ListItem","position":2,"name":"&#8220;This mod feels like a threat&#8221; Oblivion Remastered&#8217;s lockpicking is already perfect for masochists, but here&#8217;s your chance to experience a new world of pain"}]},{"@type":"WebSite","@id":"https:\/\/arcader.org\/news\/#website","url":"https:\/\/arcader.org\/news\/","name":"Arcade News","description":"Free Arcade News from the Best Online Sources","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arcader.org\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/arcader.org\/news\/#\/schema\/person\/8460f5e5076b52fb2369f2f7ce6f2839","name":"Arcade News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3fea48a614d86edd987bc7bb25f4707c69546d4b1f78ad4aa20b26316bad1f9d?s=96&d=mm&r=g","caption":"Arcade News"},"sameAs":["https:\/\/cricketgames.tv"],"url":"https:\/\/arcader.org\/news\/author\/arcade-news\/"}]}},"_links":{"self":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/1193504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/comments?post=1193504"}],"version-history":[{"count":1,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/1193504\/revisions"}],"predecessor-version":[{"id":1500822,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/posts\/1193504\/revisions\/1500822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media\/1193505"}],"wp:attachment":[{"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/media?parent=1193504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/categories?post=1193504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcader.org\/news\/wp-json\/wp\/v2\/tags?post=1193504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}